{"id":69058,"date":"2022-01-14T18:25:05","date_gmt":"2022-01-14T17:25:05","guid":{"rendered":"https:\/\/cetr.net\/?p=69058"},"modified":"2022-01-14T18:27:21","modified_gmt":"2022-01-14T17:27:21","slug":"generacion-z-explicada-el-arte-de-vivir-en-una-era-digital","status":"publish","type":"post","link":"https:\/\/cetr.net\/es\/generacion-z-explicada-el-arte-de-vivir-en-una-era-digital\/","title":{"rendered":"Generaci\u00f3n Z, explicada. EL ARTE DE VIVIR EN UNA ERA DIGITAL"},"content":{"rendered":"<p>Gen Z, Explained. THE ART OF LIVING IN A DIGITAL AGE<br \/>\nRoberta Katz, Sarah Ogilvie, Jane Shaw &amp; Linda Woodhead<br \/>\nTHE UNIVERSITY OF CHICAGO PRESS. 2021<\/p>\n<p><em>(Traducci\u00f3n nuestra)<\/em><\/p>\n<p><strong>\u00bfPOR QU\u00c9 UN LIBRO SOBRE GENERACI\u00d3N Z? <\/strong><\/p>\n<p>Los Gen Z, tambi\u00e9n llamados postmilenials, Zoomers o iGen-ers, son la primera generaci\u00f3n que nunca conocer\u00e1 el mundo sin Internet. Los m\u00e1s antiguos de la Generaci\u00f3n Z, ahora en sus veintitantos a\u00f1os, nacieron alrededor de la \u00e9poca en que la World Wide Web hizo su debut p\u00fablico en 1995. Por lo tanto, son la primera generaci\u00f3n que ha crecido solo conociendo el mundo con la posibilidad de informaci\u00f3n infinita y conectividad infinita de la era digital.<\/p>\n<p>Los miembros de la Generaci\u00f3n Z se forman y encuentran el mundo de una manera radicalmente diferente de aquellos que saben c\u00f3mo era la vida sin Internet; combinan a la perfecci\u00f3n sus mundos en l\u00ednea y fuera de l\u00ednea. Han tenido que navegar por este nuevo mundo digital en gran medida sin la gu\u00eda de sus mayores, por lo que han aprendido a abrirse camino dentro de este entorno digital en r\u00e1pido movimiento por su cuenta. Esto ha llevado a una variedad de pr\u00e1cticas diarias que son distintivas para ellos, aunque cada vez m\u00e1s adoptadas por otros, una tendencia que se aceler\u00f3 durante la pandemia de COVID-19, cuando muchos m\u00e1s aspectos de la vida de todos se conectaron. La era COVID es una era digital; marca el momento en el que el resto de la sociedad comenz\u00f3 a ponerse al d\u00eda con los miembros de la Generaci\u00f3n Z que, con su conocimiento tecnol\u00f3gico, lideran el camino.<\/p>\n<p>Este libro trata sobre las formas distintivas de ser, los valores y la visi\u00f3n del mundo que comparten muchos miembros de la Generaci\u00f3n Z. Cuenta sus historias con sus propias palabras, sus memes y mucho m\u00e1s. No afirmamos que este sea un estudio definitivo de esta generaci\u00f3n; es, m\u00e1s bien, una instant\u00e1nea de la vida de algunos miembros de la Generaci\u00f3n Z en los a\u00f1os 2016-2020, explorando qui\u00e9nes son y c\u00f3mo se desenvuelven en su vida diaria. Tambi\u00e9n utiliza la lente de la Generaci\u00f3n Z para pensar en los problemas que enfrenta nuestro mundo hoy, incluidas las paradojas y presiones que todos encontramos, al observar lo que los miembros de la Generaci\u00f3n Z ven como las grandes preocupaciones y c\u00f3mo las abordan. En ese sentido, tambi\u00e9n es un libro en el que esperamos no solo reflejar las vidas de la Generaci\u00f3n Z, sino tambi\u00e9n comprender c\u00f3mo buscan reparar tantos aspectos rotos de nuestro mundo.<\/p>\n<p><strong>C\u00d3MO LLEGAMOS A ESCRIBIR EL LIBRO <\/strong><\/p>\n<p>Los cuatro trabajamos en universidades, y durante una conversaci\u00f3n una tarde en el campus de Stanford en la primavera de 2016, nos encontramos compartiendo an\u00e9cdotas sobre nuestras experiencias de estudiantes posmilenials. Todos hab\u00edamos notado que, en los \u00faltimos a\u00f1os, los estudiantes entrantes eran sorprendentemente diferentes a los de unos a\u00f1os antes. Ten\u00edan un nuevo vocabulario para hablar sobre sus identidades y sus lugares de pertenencia; eran trabajadores pero tambi\u00e9n hac\u00edan hincapi\u00e9 en su bienestar y autocuidado; y se involucraron en el activismo de una manera distintivamente no jer\u00e1rquica y colaborativa.<\/p>\n<p>Al final de esa conversaci\u00f3n, sintiendo curiosidad por las distintas formas en las que los posmilenials se expresan, decidimos involucrarnos en nuestro propio trabajo colaborativo. Utilizar\u00edamos los m\u00e9todos combinados de nuestros campos de antropolog\u00eda, ling\u00fc\u00edstica, historia, sociolog\u00eda y estudios religiosos para idear un estudio que recopilar\u00eda datos, establecer\u00eda hechos y arrojar\u00eda luz sobre el contexto hist\u00f3rico m\u00e1s amplio para comprender mejor lo que estaba sucediendo. \u00ablos ni\u00f1os de hoy en d\u00eda.\u00bb Luego nos sumergimos en el mundo de los j\u00f3venes de dieciocho a veinticinco a\u00f1os a trav\u00e9s de entrevistas y encuestas tanto en los EE. UU. Como en el Reino Unido. Tambi\u00e9n creamos el \u00abiGen Corpus\u00bb, una colecci\u00f3n de setenta millones de palabras del lenguaje utilizado por la Generaci\u00f3n Z. De ese trabajo colaborativo surgi\u00f3 este libro.<\/p>\n<p>Utilizando sus propias palabras, mostramos c\u00f3mo la Generaci\u00f3n Z ha ido m\u00e1s all\u00e1 de navegar por este nuevo mundo para aprovecharlo para lograr una coherencia viable de creencias y valores, identidad y pertenencia. Mostramos c\u00f3mo utilizan la vasta expansi\u00f3n de informaci\u00f3n y opciones en Internet para encontrar personas de ideas afines con las que agruparse y, a trav\u00e9s de dicha exploraci\u00f3n, descubrir, perfeccionar y crear sus propias identidades. Exploramos los valores que han forjado para guiarlos en este territorio nuevo e inexplorado, y mostramos cu\u00e1n importantes son esos valores para mantener la estabilidad y la seguridad que buscan. Descubrimos sus preferencias por nuevas formas de relacionarse y actuar cuando la autoridad aparentemente se ha vuelto prescindible y la distinci\u00f3n entre fuera de l\u00ednea y en l\u00ednea se ha oscurecido. Finalmente, discutimos las tensiones y las presiones que est\u00e1n experimentando los miembros de la Generaci\u00f3n Z a medida que avanzan por este mundo en transici\u00f3n, junto con sus miedos y esperanzas sobre el futuro.<\/p>\n<p>En \u00faltima instancia, lo que notamos por primera vez en nuestro trabajo en los campus representa algo mucho m\u00e1s significativo que un simple cambio entre generaciones. La historia de la Generaci\u00f3n Z que narramos aqu\u00ed sirve como lente de enfoque; cristaliza y revela cambios y tensiones que est\u00e1n presentes en la sociedad desde hace alg\u00fan tiempo. Los posmilenials y la cultura que est\u00e1n creando nos reflejan c\u00f3mo est\u00e1n, a su manera distintiva, luchando con las innovaciones, los fracasos y las contradicciones de nuestra sociedad, muchos de los cuales se heredaron de la segunda mitad del siglo XX y afectan a todos. de nosotros.<\/p>\n<p>Por lo tanto, la experiencia de la generaci\u00f3n Z es a menudo parad\u00f3jica, incluso contradictoria. Tienen m\u00e1s \u00abvoz\u00bb que nunca (p. Ej., un meme o un video de YouTube o TikTok puede llegar a cientos de miles, incluso millones), pero tambi\u00e9n tienen un sentido de agencia disminuida \u00aben la vida real\u00bb (p. Ej., Instituciones y pol\u00edticas y los sistemas econ\u00f3micos parecen bloqueados, inaccesibles para ellos y equivocados). A menudo son optimistas sobre su propia generaci\u00f3n, pero profundamente pesimistas sobre los problemas que han heredado: cambio clim\u00e1tico, violencia, injusticia racial y de g\u00e9nero, fallas del sistema pol\u00edtico y pocas posibilidades de tener una casa propia o mejorar el nivel de riqueza de sus padres.<\/p>\n<p>Los Gen Zers navegan por estas paradojas utilizando las nuevas herramientas, generalmente digitales, que tienen a mano. Destacamos tres estrategias principales. Primero, tienen muy claro qui\u00e9nes son y usan esa claridad de identidad para autodefinirse y rechazar presiones y demandas no deseadas (por ejemplo, \u00abno, eso no es apropiado para quien soy\u00bb). En segundo lugar, se unen a comunidades (principalmente en l\u00ednea) que encajan, apoyan y ayudan a refinar su identidad personal y colectiva, su prop\u00f3sito y (para algunos) activismo. En tercer lugar, rechazan la jerarqu\u00eda y adoptan distribuciones m\u00e1s amplias de voz y poder sobre la base de la igualdad y la colaboraci\u00f3n y teniendo un conjunto claro de valores.<\/p>\n<p>Sin embargo, como exponemos en este libro, la Generaci\u00f3n Z lleva una pesada carga: a saber, \u00bfc\u00f3mo podemos vivir todos en este mundo dram\u00e1ticamente cambiado? Los posmilenials est\u00e1n demostrando mucho de lo que est\u00e1 en juego para la humanidad frente a una sociedad orientada a la red y definida digitalmente que se mueve con una escala, alcance y velocidad sin precedentes. Cada vez est\u00e1 m\u00e1s claro que se necesita una reconstrucci\u00f3n social masiva y que el trabajo requerir\u00e1 que todos participen. Hasta ahora, los posmilenials son eficaces a la hora de modelar alternativas, a menudo, aunque no solo, dentro de las esferas limitadas en las que operan. Ejemplos obvios son la moderaci\u00f3n en l\u00ednea y el activismo estudiantil en el campus, ambos de los cuales discutimos. Sin embargo, no siempre entienden o saben c\u00f3mo operar o cambiar las instituciones y jerarqu\u00edas existentes, y esto a veces puede llevar a enfrentamientos con sus mayores. Esto puede suceder incluso cuando ellos y sus mayores tienen valores y aspiraciones similares porque la forma de hacer las cosas de la Generaci\u00f3n Z ha sido profundamente moldeada por la tecnolog\u00eda digital, conduciendo a nuevos m\u00e9todos de trabajo, conexi\u00f3n con otros, activismo y mucho m\u00e1s. A su vez, los miembros de la Generaci\u00f3n Z podr\u00edan argumentar que muchas instituciones existentes, con sus jerarqu\u00edas relacionadas y modos de hacer y ser anticuados y en gran parte anal\u00f3gicos, son incapaces de ser los lugares de cambio que el mundo necesita.<\/p>\n<p>Por mucho que los postmilenials tengan que aprender, tambi\u00e9n tienen mucho que ense\u00f1ar. Est\u00e1n tratando de humanizar un mundo inhumano e intratable que parece encaminarse al desastre. Sus habilidades son complementarias a las generaciones predigitales. Aquellos de nosotros que somos mayores, y nos incluimos en esa cohorte, por supuesto, necesitamos trabajar con postmilenials y aprender de sus formas alternativas de ser y hacer las cosas, y los postmilenials necesitan trabajar con otras generaciones para incorporar el cambio que est\u00e1n modelando en sus propias esferas de acci\u00f3n de formas m\u00e1s amplias y duraderas. Tienen grandes conocimientos para el resto de nosotros; sin embargo, existen l\u00edmites sobre lo que pueden lograr solos. Quiz\u00e1s podamos convertir \u00abOK Boomer\u00bb en un t\u00e9rmino de colegialidad en lugar del ep\u00edteto en el que se ha convertido, de modo que podamos trabajar juntos para reconstruir nuestras instituciones sociales de la era industrial que se derrumban en algo que refleje mejor las necesidades de los humanos de la era digital.<\/p>\n<p>Una crisis acecha para todos a menos que encontremos formas de cambiar. Como este libro intenta mostrar, los miembros de la Generaci\u00f3n Z tienen ideas sobre el tipo de mundo que les gustar\u00eda crear. Al escuchar atentamente lo que est\u00e1n diciendo, podemos apreciar las lecciones que tienen para ense\u00f1arnos: sea real, sea qui\u00e9n eres, sea responsable de su propio bienestar, apoye a sus amigos, abra las instituciones a los talentos de muchos, no de unos pocos, abrace la diversidad, haga que el mundo sea m\u00e1s amable, viva seg\u00fan sus valores. En las p\u00e1ginas siguientes compartimos no solo lo que podemos aprender de y sobre la Generaci\u00f3n Z, sino por qu\u00e9 creemos que podr\u00edan ocurrir cambios sociales a\u00fan m\u00e1s significativos a medida que los miembros de esta generaci\u00f3n avancen hacia la edad adulta y la esfera p\u00fablica.<\/p>\n<p>Nuestro objetivo a lo largo de nuestra investigaci\u00f3n y la redacci\u00f3n de este libro no es patologizar ni idealizar a la Generaci\u00f3n Z, sino comprenderlos en sus propios t\u00e9rminos y como herederos de los problemas que todos enfrentamos. Hemos tratado de observar sus m\u00e9todos para abordar esos problemas y escuchar con respeto cr\u00edtico sus soluciones. Para aquellos de ustedes (mayores) lectores que est\u00e1n desconcertados por los posmileniales, esperamos que este libro les permita comprenderlos mejor y sin un juicio inmediato. Para aquellos de ustedes lectores que son posmileniales, esperamos que encuentren al menos algunos aspectos de ustedes mismos representados con precisi\u00f3n aqu\u00ed y que encuentren el estudio \u00fatil para reflexionar sobre lo que ustedes y sus compa\u00f1eros podr\u00edan contribuir especialmente al mundo. Estamos todos juntos en esto, y como muestra este libro, tenemos cosas importantes que aprender unos de otros a trav\u00e9s de las generaciones.<\/p>\n<p><strong>C\u00d3MO INVESTIGAMOS Y ESCRIBIMOS EL LIBRO <\/strong><\/p>\n<p>Nuestro objetivo en todo momento ha sido comprender y presentar a los Gen Zers que hemos estudiado en sus propios t\u00e9rminos y, en particular, en sus propias palabras, mostrando c\u00f3mo se distinguen. Nos tom\u00f3 un tiempo hablar juntos para averiguar exactamente c\u00f3mo \u00edbamos a hacer eso. La mentalidad abierta de nuestros patrocinadores, la Fundaci\u00f3n Knight, y el apoyo de nuestro anfitri\u00f3n institucional, el Centro de Estudios Avanzados en Ciencias del Comportamiento en Stanford, nos dio la libertad de trabajar en colaboraci\u00f3n y hacer crecer el proyecto org\u00e1nicamente, ajustando nuestro enfoque como Los hallazgos pusieron en tela de juicio algunas de nuestras ideas iniciales e introdujeron nuevos temas. Nuestro tema traspas\u00f3 los l\u00edmites disciplinarios y requiri\u00f3 la experiencia que cada uno de nosotros aport\u00f3 al proyecto. Tambi\u00e9n aprendimos de colegas en psicolog\u00eda social y estudios de comunicaci\u00f3n.<\/p>\n<p>En 2017, comenzamos con una serie de entrevistas con estudiantes posmilenialistas de dieciocho a veinticinco a\u00f1os, en su mayor\u00eda, pero no solo estudiantes universitarios, cuyas palabras son fundamentales para la textura y la narrativa de este libro. Capacitamos a los estudiantes asistentes de investigaci\u00f3n para que hicieran las entrevistas, con el argumento de que nosotros, y ellos, pensamos que tales conversaciones entre pares provocar\u00edan respuestas m\u00e1s interesantes y m\u00e1s honestas. Se pregunt\u00f3 a los entrevistados sobre su uso de la tecnolog\u00eda, c\u00f3mo se ven a s\u00ed mismos en el mundo, sus valores y c\u00f3mo se relacionan con los dem\u00e1s, incluidos sus familiares, amigos y conocidos. Mantuvimos las preguntas lo m\u00e1s amplias y abiertas posible y nos aseguramos de tener una muestra representativa de estudiantes de una amplia gama de antecedentes socioecon\u00f3micos, culturas, razas y etnias y religiones. Tambi\u00e9n complementamos las entrevistas con algunos grupos focales, generando conversaciones entre estudiantes de diferentes grupos en cada campus. Debemos se\u00f1alar aqu\u00ed que cuando citamos a los estudiantes, asignamos diferentes nombres para anonimizarlos. Deliberadamente no usamos sus marcadores de identidad (por ejemplo, origen \u00e9tnico, g\u00e9nero, orientaci\u00f3n sexual, nacionalidad), ni notamos de qu\u00e9 campus provienen, a menos que sea relevante para el tema que se est\u00e1 discutiendo, para proteger esas identidades y garantizar el anonimato.<\/p>\n<p>Las entrevistas se realizaron generalmente en tres campus: Foothill Community College en el norte de California, que atiende principalmente a estudiantes que buscan t\u00edtulos asociados de dos a\u00f1os;la Universidad de Lancaster, una universidad p\u00fablica de investigaci\u00f3n en el Reino Unido en el coraz\u00f3n de industrias manufactureras en declive; y la Universidad de Stanford privada de primer nivel con sus estrechos v\u00ednculos con Silicon Valley y la industria tecnol\u00f3gica. Cada uno representa un tipo distintivo de instituci\u00f3n de educaci\u00f3n superior.<\/p>\n<p>En unos pocos a\u00f1os, obtuvimos datos de 120 entrevistas formales de los tres campus y de un pu\u00f1ado de grupos focales. El siguiente paso fue comparar los hallazgos de esta investigaci\u00f3n cualitativa con sus pares en la poblaci\u00f3n en general, en particular, incluidos aquellos que no estaban cursando estudios superiores. Hicimos esto de dos maneras, recopilando datos cuantitativos con m\u00e9todos ling\u00fc\u00edsticos y sociol\u00f3gicos.<\/p>\n<p>En primer lugar, partiendo de la premisa de que el lenguaje es clave para la cultura, exploramos el lenguaje de los posmilenials a partir de una variedad de fuentes. Creamos el iGen Corpus, una colecci\u00f3n de setenta millones de palabras del idioma ingl\u00e9s espec\u00edfico de la edad en forma de texto, imagen y video extra\u00eddos de las redes sociales, transcripciones de video alineadas en el tiempo, memes y nuestras entrevistas. El iGen Corpus comprende lenguaje postmilenial de una variedad de plataformas de redes sociales: social (Twitter), juegos (Twitch), discusi\u00f3n (Reddit), tablero de im\u00e1genes (4chan) y video (YouTube). Aplicamos algoritmos de aprendizaje autom\u00e1tico cuando fue necesario para extraer el idioma de las personas de nuestro grupo de edad. El iGen Corpus tambi\u00e9n incluye memes, emoji y copypastas (fragmentos copiados y pegados de texto editado ir\u00f3nicamente) de una variedad de plataformas, incluidas Facebook e Instagram. Esta gran colecci\u00f3n de lenguaje postmilenial nos permiti\u00f3 comparar los valores y opiniones de esta cohorte con la poblaci\u00f3n en general (todas las edades) representada por colecciones comparables de lenguaje como el British National Corpus (BNC) en el Reino Unido y el Corpus of Contemporary Ingl\u00e9s americano (COCA) en los Estados Unidos. Como es evidente a lo largo de este libro, este an\u00e1lisis computacional nos permiti\u00f3 determinar si ciertas palabras y conceptos ten\u00edan m\u00e1s relevancia, o \u201cclave\u201d, para los posmileniales que para la poblaci\u00f3n en general.<\/p>\n<p>Despu\u00e9s de concluir una gran parte de las entrevistas y tener algunos hallazgos iniciales, realizamos dos encuestas a j\u00f3venes de dieciocho a veinticinco a\u00f1os en general, tanto con educaci\u00f3n universitaria como no, en los Estados Unidos y el Reino Unido. Los resultados nos permitieron ver cu\u00e1n representativos de la poblaci\u00f3n en general son los hallazgos de nuestra entrevista y ver el panorama m\u00e1s amplio. Juntos, el corpus y las encuestas sirven al estudio como una toma de referencia en una pel\u00edcula, sacando la c\u00e1mara a lo alto y ancho, para revelar los contornos generales del grupo de edad en cuesti\u00f3n. La observaci\u00f3n participante, las entrevistas y los grupos focales nos permiten enfocarnos m\u00e1s de cerca, aportando profundidad, textura y riqueza humana.<\/p>\n<p>Finalmente, encargamos una serie de art\u00edculos breves sobre este grupo de edad para una revista de estudios sociales en l\u00ednea, Est\u00e1ndar del Pac\u00edfico. Invitamos a una muestra representativa de los propios miembros de la Generaci\u00f3n Z, adem\u00e1s de maestros, padres, periodistas, acad\u00e9micos y administradores de educaci\u00f3n superior, as\u00ed como a otras personas que trabajan en las artes, la tecnolog\u00eda, la ciencia y la religi\u00f3n, para escribir sobre su perspectiva sobre lo que es distintivo. sobre posmilenials, relaciones intergeneracionales y mucho m\u00e1s.1 Puede encontrar informaci\u00f3n adicional sobre nuestra metodolog\u00eda en el ap\u00e9ndice.<\/p>\n<p>Esto plantea la cuesti\u00f3n \u00abgeneracional\u00bb. Durante los a\u00f1os que estuvimos ocupados reuniendo este material, aparecieron varios libros ampliamente debatidos sobre la Generaci\u00f3n Z, la iGen y los posmileniales. Han dado forma a la conversaci\u00f3n en la que ahora hablamos, aunque nuestra agenda es diferente. Los estudios generacionales asumen que cada generaci\u00f3n, que tradicionalmente dura unos veinte a\u00f1os, es diferente de la que la precedi\u00f3. Al notar diferencias significativas entre los j\u00f3venes y los millennials, tambi\u00e9n llamados \u00abGeneraci\u00f3n Y\u00bb, que nacieron alrededor y despu\u00e9s de 1980, estos estudios concluyeron que necesit\u00e1bamos una nueva forma de etiquetar a los nacidos alrededor y despu\u00e9s de 1995. El consenso parece estar construyendo alrededor de tres tales etiquetas: Gen Z, postmilenials y, m\u00e1s recientemente, Zoomers. Como se se\u00f1al\u00f3 anteriormente, este libro no es un estudio definitivo de la Generaci\u00f3n Z, pero intentamos proporcionar un contexto hist\u00f3rico para nuestros hallazgos. Nos basamos en la historia para ubicar las experiencias e ideas de la Generaci\u00f3n Z, entre otras cosas, su adopci\u00f3n de una identidad finamente granulada, en una trayectoria m\u00e1s larga. De vez en cuando proporcionamos comentarios y pensamientos de la Generaci\u00f3n Z sobre las generaciones posteriores (Generaci\u00f3n Alfa, nacida en 2010 o despu\u00e9s) y antes (Gen Y, Gen X y boomers). Adem\u00e1s, este no es un estudio definitivo de los postmilenials en todo el mundo: nuestra muestra no lo permite. Dicho esto, esperamos que ofrezca una instant\u00e1nea de la Generaci\u00f3n Z en los Estados Unidos y Gran Breta\u00f1a que sea esclarecedora y \u00fatil. Tambi\u00e9n esperamos que pueda inspirar a otros a investigar a la Generaci\u00f3n Z en otras culturas y sociedades.<\/p>\n<p>Una de las primeras cosas que aprendimos de la generaci\u00f3n Z es el gran valor que le dan a la colaboraci\u00f3n; en sus palabras, les gusta \u00abcolaborar\u00bb. De acuerdo con este tema, este proyecto de investigaci\u00f3n y el libro resultante han sido totalmente colaborativos. Los cuatro hemos escrito este libro juntos, con una sola voz; Esperamos que disfrute leyendo el libro tanto como nosotros disfrutamos escribi\u00e9ndolo. Tambi\u00e9n esperamos que aprenda tanto sobre usted y los dem\u00e1s al leer el libro como nosotros al escribirlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este libro escrito por cuatro profesoras  de diversas universidades estadounidenses y de Reino Unido Roberta Katz, Sarah Ogilvie, Jane Shaw y Linda Woodhead (Universidad de Stanford, Harris Manchester College, Oxford University, Lancaster University ) a partir de 120 entrevistas a estudiantes, trata sobre las formas distintivas de ser, los valores y la visi\u00f3n del mundo que comparten muchos miembros de la Generaci\u00f3n Z. Cuenta sus historias con sus propias palabras, sus memes y mucho m\u00e1s. No pretende ser un estudio definitivo de esta generaci\u00f3n; es, m\u00e1s bien, una instant\u00e1nea de la vida de algunos miembros de la Generaci\u00f3n Z en los a\u00f1os 2016-2020, explorando qui\u00e9nes son y c\u00f3mo se desenvuelven en su vida diaria. Tambi\u00e9n utiliza la lente de la Generaci\u00f3n Z para pensar en los problemas que enfrenta nuestro mundo hoy, incluidas las paradojas y presiones que todos encontramos, al observar lo que los miembros de la Generaci\u00f3n Z ven como las grandes preocupaciones y c\u00f3mo las abordan. En ese sentido, tambi\u00e9n es un libro en el no solo espera reflejar las vidas de la Generaci\u00f3n Z, sino tambi\u00e9n comprender c\u00f3mo buscan reparar tantos aspectos rotos de nuestro mundo.<\/p>\n","protected":false},"author":1,"featured_media":69055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[145,233,161],"tags":[],"post_series":[],"class_list":["post-69058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-home-es","category-sociedad-en-cambio","entry","has-media"],"acf":[],"_links":{"self":[{"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/posts\/69058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/comments?post=69058"}],"version-history":[{"count":2,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/posts\/69058\/revisions"}],"predecessor-version":[{"id":69062,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/posts\/69058\/revisions\/69062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/media\/69055"}],"wp:attachment":[{"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/media?parent=69058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/categories?post=69058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/tags?post=69058"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/cetr.net\/es\/wp-json\/wp\/v2\/post_series?post=69058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}